{"id":103725,"date":"2024-05-30T19:37:56","date_gmt":"2024-05-30T18:37:56","guid":{"rendered":"https:\/\/www.quartix.com\/?post_type=landing_page&#038;p=103725"},"modified":"2024-06-07T18:39:44","modified_gmt":"2024-06-07T17:39:44","slug":"seguimiento-de-vehiculos-2024-v2","status":"publish","type":"landing_page","link":"https:\/\/www.quartix.com\/es-es\/in\/seguimiento-de-vehiculos-2024-v2\/","title":{"rendered":"Vehicle Tracking 2024 V2"},"content":{"rendered":"<section  class=\"qtx-pagebuilder-section qtx-pagebuilder-section-title widthwrapper\">\r\n    <h1>Seguimiento de veh\u00edculos f\u00e1cil de usar desde solo \u20ac7.90 por veh\u00edculo al mes.<\/h1>\r\n<\/section>\n\n<section  class=\"qtx-pagebuilder-section qtx-pagebuilder-section-text widthwrapper\">\r\n    <p class=\"p1\" style=\"text-align: center;\">Siga sus veh\u00edculos en tiempo real, mejore rutas y ahorre dinero. Obtenga el mejor rendimiento de sus furgonetas con facilidad. Despl\u00e1cese hacia abajo para explorar precios y caracter\u00edsticas.<\/p>\n<\/section>\r\n\n\n<section  class=\"qtx-pagebuilder-section qtx-pagebuilder-section-pricing\">\r\n    <div class=\"widthwrapper\">\r\n        <div class=\"pricingcontainer\">\r\n                            <div class=\"plan \">\r\n                                        <div class=\"planinner\">\r\n                        <h3>Info Point<\/h3>                        <p class=\"pricesubline\">desde<\/p>                        <h3 class=\"price\"> <span class=\"old\">\u20ac9.99<\/span> \u20ac7.90<\/h3>                        <p class=\"pricesubline\">por veh\u00edculo\/mes<\/p>                        <img decoding=\"async\" src=\"https:\/\/www.quartix.com\/content\/uploads\/2024\/05\/ES-live-tracking-screen.png\" alt=\"ES live tracking screen\">                        <a class=\"btn btn-green\" href=\"#formmodal\" target=\"\">\r\n                            Comience hoy                        <\/a>                        <hr>\r\n                        <div class=\"list\">\r\n                            <ul>\r\n                                                                    <li><span class=\"fa-li\"><i class=\"fas fa-check-circle\"><\/i><\/span>Seguimiento de veh\u00edculos por GPS (actualizaciones cada 2 minutos)<\/li>\r\n                                                                    <li><span class=\"fa-li\"><i class=\"fas fa-check-circle\"><\/i><\/span>Registros de veh\u00edculos\/conductores<\/li>\r\n                                                                    <li><span class=\"fa-li\"><i class=\"fas fa-check-circle\"><\/i><\/span>Mapas de rutas<\/li>\r\n                                                                    <li><span class=\"fa-li\"><i class=\"fas fa-check-circle\"><\/i><\/span>Software basado en la nube<\/li>\r\n                                                                    <li><span class=\"fa-li\"><i class=\"fas fa-check-circle\"><\/i><\/span>Acceso a la aplicaci\u00f3n m\u00f3vil incluido<\/li>\r\n                                                            <\/ul>\r\n                        <\/div>\r\n                    <\/div>\r\n                <\/div>\r\n                            <div class=\"plan ispopular\">\r\n                                            <div class=\"popular\"><span>M\u00e1s popular<\/span><\/div>\r\n                                        <div class=\"planinner\">\r\n                        <h3>Info Plus<\/h3>                        <p class=\"pricesubline\">desde<\/p>                        <h3 class=\"price\"> <span class=\"old\">\u20ac11.99<\/span> \u20ac8.90<\/h3>                        <p class=\"pricesubline\">por veh\u00edculo\/mes<\/p>                        <img decoding=\"async\" src=\"https:\/\/www.quartix.com\/content\/uploads\/2024\/05\/ES-dashboards-with-driving-style-with-vehicles-on-mob.png\" alt=\"ES dashboards with driving style with vehicles on mob\">                        <a class=\"btn btn-green\" href=\"#formmodal\" target=\"\">\r\n                            Comience hoy                        <\/a>                        <hr>\r\n                        <div class=\"list\">\r\n                            <ul>\r\n                                                                    <li><span class=\"fa-li\"><i class=\"fas fa-check-circle\"><\/i><\/span>Seguimiento de veh\u00edculos por GPS (actualizaciones cada minuto)<\/li>\r\n                                                                    <li><span class=\"fa-li\"><i class=\"fas fa-check-circle\"><\/i><\/span>Registros de veh\u00edculos\/conductores<\/li>\r\n                                                                    <li><span class=\"fa-li\"><i class=\"fas fa-check-circle\"><\/i><\/span>Mapas de rutas<\/li>\r\n                                                                    <li><span class=\"fa-li\"><i class=\"fas fa-check-circle\"><\/i><\/span>Software basado en la nube<\/li>\r\n                                                                    <li><span class=\"fa-li\"><i class=\"fas fa-check-circle\"><\/i><\/span>Acceso a la aplicaci\u00f3n m\u00f3vil incluido<\/li>\r\n                                                                    <li><span class=\"fa-li\"><i class=\"fas fa-check-circle\"><\/i><\/span>Comportamiento del conductor<\/li>\r\n                                                                    <li><span class=\"fa-li\"><i class=\"fas fa-check-circle\"><\/i><\/span>Geocercas<\/li>\r\n                                                                    <li><span class=\"fa-li\"><i class=\"fas fa-check-circle\"><\/i><\/span>Informes de gesti\u00f3n<\/li>\r\n                                                            <\/ul>\r\n                        <\/div>\r\n                    <\/div>\r\n                <\/div>\r\n                            <div class=\"plan \">\r\n                                        <div class=\"planinner\">\r\n                        <h3>Info Plus + Identificaci\u00f3n del Conductor<\/h3>                                                <h3 class=\"price\"> Precios a medida<\/h3>                        <p class=\"pricesubline\">por veh\u00edculo\/mes<\/p>                        <img decoding=\"async\" src=\"https:\/\/www.quartix.com\/content\/uploads\/2024\/05\/Es-Quartix-screens-and-Driver-ID.png\" alt=\"Es Quartix screens and Driver ID\">                        <a class=\"btn btn-green\" href=\"#formmodal\" target=\"\">\r\n                            Comience hoy                        <\/a>                        <hr>\r\n                        <div class=\"list\">\r\n                            <ul>\r\n                                                                    <li><span class=\"fa-li\"><i class=\"fas fa-check-circle\"><\/i><\/span>Seguimiento de veh\u00edculos por GPS (actualizaciones cada minuto)<\/li>\r\n                                                                    <li><span class=\"fa-li\"><i class=\"fas fa-check-circle\"><\/i><\/span>Registros de veh\u00edculos\/conductores<\/li>\r\n                                                                    <li><span class=\"fa-li\"><i class=\"fas fa-check-circle\"><\/i><\/span>Mapas de rutas<\/li>\r\n                                                                    <li><span class=\"fa-li\"><i class=\"fas fa-check-circle\"><\/i><\/span>Software basado en la nube<\/li>\r\n                                                                    <li><span class=\"fa-li\"><i class=\"fas fa-check-circle\"><\/i><\/span>Acceso a la aplicaci\u00f3n m\u00f3vil incluido<\/li>\r\n                                                                    <li><span class=\"fa-li\"><i class=\"fas fa-check-circle\"><\/i><\/span>Comportamiento del conductor<\/li>\r\n                                                                    <li><span class=\"fa-li\"><i class=\"fas fa-check-circle\"><\/i><\/span>Geocercas<\/li>\r\n                                                                    <li><span class=\"fa-li\"><i class=\"fas fa-check-circle\"><\/i><\/span>Informes de gesti\u00f3n<\/li>\r\n                                                                    <li><span class=\"fa-li\"><i class=\"fas fa-check-circle\"><\/i><\/span><span class=\"bold\">Identificaci\u00f3n del Conductor<\/span><\/li>\r\n                                                            <\/ul>\r\n                        <\/div>\r\n                    <\/div>\r\n                <\/div>\r\n                        <div class=\"optionals\">\r\n                <h4>Complementos Opcionales<\/h4>                                    <div class=\"optional\">\r\n                        <div class=\"card\">\r\n                            <h4>Etiquetas de identificaci\u00f3n del conductor<\/h4>\r\n                            <p>Identifique qu\u00e9 empleado est\u00e1 conduciendo en todo momento con etiquetas RFID, mejorando la responsabilidad y la seguridad.<\/p>\r\n                                                        <img decoding=\"async\" src=\"https:\/\/www.quartix.com\/content\/uploads\/2024\/05\/Image-22.png\" alt=\"\">\r\n                                                    <\/div>\r\n                    <\/div>\r\n                            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/section>\r\n\r\n<script nonce=\"\" nonce=\"\">\r\n    jQuery(function($) {\r\n        $( document ).ready(function(){\r\n            $('.qtx-pagebuilder-section-pricing .pricingcontainer').slick({\r\n                arrows: false,\r\n                dots: false,\r\n                slidesToShow: 4,\r\n                slidesToScroll: 1,\r\n                infinite: false,\r\n                responsive: [\r\n                    {\r\n                    \/\/ breakpoint: 1024,\r\n                    breakpoint: 1500,\r\n                    settings: {\r\n                        slidesToShow: 2,\r\n                        infinite: true,\r\n                        centerMode: true,\r\n                        dots: true,\r\n                        initialSlide: 1,\r\n                        }\r\n                    },\r\n                    {\r\n                    breakpoint: 768,\r\n                    settings: {\r\n                        slidesToShow: 1,\r\n                        centerMode: true,\r\n                        infinite: true,\r\n                        dots: true,\r\n                        initialSlide: 1,\r\n                        } \r\n                    },\r\n                    {\r\n                    breakpoint: 450,\r\n                    settings: {\r\n                        slidesToShow: 1,\r\n                        centerMode: false,\r\n                        infinite: true,\r\n                        dots: true,\r\n                        initialSlide: 1,\r\n                        } \r\n                    },\r\n                ]\r\n            });\r\n        });\r\n    });\r\n\r\n<\/script>\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<section  class=\"qtx-pagebuilder-section qtx-pagebuilder-section-expfeatures exp1740655323\">\r\n<div class=\"widthtitle\">\r\n    <h2>\u00a1Rastree sus veh\u00edculos en cualquier momento y lugar! \u00danase a m\u00e1s de 30,000 empresas que utilizan Quartix.<\/h2>\r\n<\/div>\r\n<div class=\"widthwrapper\">\r\n    <div class=\"features\">\r\n                            <div class=\"feature open\">\r\n                <div class=\"number\">1<\/div>\r\n                <h3>Seguimiento en Tiempo Real<\/h3>\r\n                <p class=\"featuredesc\">Vea los movimientos de sus veh\u00edculos en tiempo real. Sepa d\u00f3nde est\u00e1 cada veh\u00edculo para planificar mejores rutas, ahorrar combustible y entregar a tiempo. Esto ahorra dinero y hace que los clientes est\u00e9n m\u00e1s satisfechos.<\/p>\r\n            <\/div>\r\n                    <div class=\"feature \">\r\n                <div class=\"number\">2<\/div>\r\n                <h3>Mejor rendimiento del conductor<\/h3>\r\n                <p class=\"featuredesc\">Observe el comportamiento del conductor con an\u00e1lisis detallados. Encuentre formas de mejorar, promover la conducci\u00f3n segura y reducir los accidentes. Conducir mejor significa menores costos de mantenimiento y un entorno de trabajo m\u00e1s seguro.<\/p>\r\n            <\/div>\r\n                    <div class=\"feature \">\r\n                <div class=\"number\">3<\/div>\r\n                <h3>Optimizaci\u00f3n del Mantenimiento de la Flota<\/h3>\r\n                <p class=\"featuredesc\">Mantenga sus veh\u00edculos en \u00f3ptimas condiciones con alertas de mantenimiento autom\u00e1ticas. Controle la salud de los veh\u00edculos y solucione los problemas temprano para evitar grandes inconvenientes. Esto reduce el tiempo de inactividad y prolonga la vida \u00fatil de los veh\u00edculos.<\/p>\r\n            <\/div>\r\n                    <div class=\"feature \">\r\n                <div class=\"number\">4<\/div>\r\n                <h3>Informes detallados<\/h3>\r\n                <p class=\"featuredesc\">Obtenga informes sobre el uso de veh\u00edculos, el rendimiento del conductor y la eficiencia del combustible. Utilice estos datos para tomar decisiones inteligentes, mejorar las operaciones y hacer crecer su negocio. Mant\u00e9ngase por delante de la competencia con informaci\u00f3n completa.<\/p>\r\n            <\/div>\r\n                    <div class=\"feature \">\r\n                <div class=\"number\">5<\/div>\r\n                <h3>Mejorar el servicio al cliente<\/h3>\r\n                <p class=\"featuredesc\">Proporcione a sus clientes tiempos de entrega precisos y actualizaciones. El seguimiento en tiempo real le permite responder r\u00e1pidamente y hacer cambios seg\u00fan sea necesario. Esto genera confianza y lealtad a trav\u00e9s de una mayor transparencia y fiabilidad.<\/p>\r\n            <\/div>\r\n            <\/div>\r\n    <div class=\"image\">\r\n        <img decoding=\"async\" src=\"https:\/\/www.quartix.com\/content\/uploads\/2024\/05\/ES-live-tracking-screen.png\" alt=\"ES live tracking screen\">\r\n    <\/div>\r\n<\/div>\r\n<\/section>\r\n\r\n<script nonce=\"\" nonce=\"\">\r\n    jQuery(function($) {\r\n        $(document).ready(function() {\r\n            var $section = $('.exp1740655323'); \/\/ Scope to this section only\r\n            var $features = $section.find('.features');\r\n            var $image = $section.find('.image');\r\n            \r\n            \/\/ Hide all feature descriptions except the open one\r\n            $features.find('.featuredesc').hide();\r\n            $features.find('.feature.open .featuredesc').show();\r\n\r\n            \/\/ Toggle feature description on header click\r\n            $features.find('h3, .number').click(function() {\r\n                var $feature = $(this).closest('.feature');\r\n                if (!$feature.hasClass('open')) {\r\n                    \/\/ Close all features\r\n                    $features.find('.feature.open')\r\n                        .removeClass('open')\r\n                        .find('.featuredesc')\r\n                        .slideUp(400);\r\n                    \/\/ Open clicked feature\r\n                    $feature\r\n                        .addClass('open')\r\n                        .find('.featuredesc')\r\n                        .slideDown(400);\r\n                } else {\r\n                    \/\/ If already open, close it\r\n                    $feature\r\n                        .removeClass('open')\r\n                        .find('.featuredesc')\r\n                        .slideUp(400);\r\n                }\r\n                \/\/ Adjust height after animation\r\n                setTimeout(matchHeights, 450);\r\n            });\r\n\r\n            function matchHeights() {\r\n            if (window.innerWidth >= 992) {\r\n                var featuresHeight = $features.outerHeight();\r\n                var imageHeight = $image.outerHeight();\r\n                var maxHeight = Math.max(featuresHeight, imageHeight);\r\n                $features.css('min-height', maxHeight + 'px');\r\n                $image.css('min-height', maxHeight + 'px');\r\n            } else {\r\n                \/\/ Reset heights on smaller screens\r\n                $features.css('min-height', '');\r\n                $image.css('min-height', '');\r\n            }\r\n        }\r\n\r\n            $(window).on('load resize', matchHeights);\r\n        });\r\n    });\r\n<\/script>\r\n\r\n\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Descubra c\u00f3mo nuestro sistema de gesti\u00f3n de flotas transforma los negocios<\/h2>\n\n\n        <a href=\"https:\/\/www.youtube.com\/watch?v=e9rl20mhWjI\" data-lity  class=\"lightbox thumbnail\">\r\n            <div class=\"videooverlay\"><\/div>                        <figure class=\"wp-block-image\">\r\n                                    <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/www.quartix.com\/content\/uploads\/2024\/05\/Quartix-Spain-video-1000x563.png\" alt=\"Quartix Spain video\">\r\n                                <\/figure>\r\n                    <\/a>\r\n        \n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<section  class=\"qtx-pagebuilder-section qtx-pagebuilder-section-title widthwrapper\">\r\n    <h1>Descubra c\u00f3mo el seguimiento de veh\u00edculos transforma negocios reales<\/h1>\r\n<\/section>\n\n\r\n<section  class=\"qtx-pagebuilder-section qtx-pagebuilder-section-benefits \">\r\n    <div class=\"widthwrapper\">\r\n        <div class=\"benefits\">\r\n                            <h3>Hacer que las operaciones sean m\u00e1s fluidas<\/h3>\r\n                                        <p>Mantenga un seguimiento de sus veh\u00edculos en tiempo real. Planifique mejores rutas para ahorrar combustible y reducir los tiempos de espera. Una mejor gesti\u00f3n de veh\u00edculos ahorra dinero y aumenta la productividad.<\/p>\r\n                                        <h4>Beneficios clave:<\/h4>\r\n                                        <ul>\r\n                                                                        <li>\r\n                                <span class=\"fa-li\"><i class=\"fas fa-check-circle\"><\/i><\/span>\r\n                                Seguimiento de veh\u00edculos en vivo                            <\/li>\r\n                                                                                                <li>\r\n                                <span class=\"fa-li\"><i class=\"fas fa-check-circle\"><\/i><\/span>\r\n                                Mejor planificaci\u00f3n de rutas                            <\/li>\r\n                                                                                                <li>\r\n                                <span class=\"fa-li\"><i class=\"fas fa-check-circle\"><\/i><\/span>\r\n                                Menos tiempo de espera                            <\/li>\r\n                                                            <\/ul>\r\n                                        <a href=\"#formmodal\" class=\"btn btn-green btn-inline\">\r\n                    Contacte a nuestro equipo                <\/a>\r\n                    <\/div>  \r\n                    <div class=\"image\">\r\n                <img decoding=\"async\" src=\"https:\/\/www.quartix.com\/content\/uploads\/2024\/05\/ES-route-maps-screen.png\" alt=\"ES route maps screen\">\r\n            <\/div>\r\n            <\/div>\r\n<\/section>\n\n\r\n<section  class=\"qtx-pagebuilder-section qtx-pagebuilder-section-benefits flipped\">\r\n    <div class=\"widthwrapper\">\r\n        <div class=\"benefits\">\r\n                            <h3>Mejorar la seguridad<\/h3>\r\n                                        <p>Cree un entorno m\u00e1s seguro con nuestro sistema de seguimiento. Observe el comportamiento de los conductores, reciba alertas por conducci\u00f3n insegura y siga las normas de seguridad. Conducir de manera m\u00e1s segura significa menos accidentes y menores costos.<\/p>\r\n                                        <h4>Beneficios clave:<\/h4>\r\n                                        <ul>\r\n                                                                        <li>\r\n                                <span class=\"fa-li\"><i class=\"fas fa-check-circle\"><\/i><\/span>\r\n                                Monitoreo del comportamiento del conductor                            <\/li>\r\n                                                                                                <li>\r\n                                <span class=\"fa-li\"><i class=\"fas fa-check-circle\"><\/i><\/span>\r\n                                Alertas de seguridad y notificaciones                            <\/li>\r\n                                                                                                <li>\r\n                                <span class=\"fa-li\"><i class=\"fas fa-check-circle\"><\/i><\/span>\r\n                                Cumplimiento de regulaciones                            <\/li>\r\n                                                            <\/ul>\r\n                                        <a href=\"#formmodal\" class=\"btn btn-green btn-inline\">\r\n                    Contacte a nuestro equipo                <\/a>\r\n                    <\/div>  \r\n                    <div class=\"image\">\r\n                <img decoding=\"async\" src=\"https:\/\/www.quartix.com\/content\/uploads\/2024\/05\/Artboard-\u2013-9.png\" alt=\"\">\r\n            <\/div>\r\n            <\/div>\r\n<\/section>\n\n\r\n<section  class=\"qtx-pagebuilder-section qtx-pagebuilder-section-benefits \">\r\n    <div class=\"widthwrapper\">\r\n        <div class=\"benefits\">\r\n                            <h3>Mantenga a sus clientes felices<\/h3>\r\n                                        <p>Ofrezca un excelente servicio con actualizaciones precisas. Siga las entregas en tiempo real, hable f\u00e1cilmente con sus clientes y aseg\u00farese de que las entregas lleguen a tiempo. Una mejor comunicaci\u00f3n genera confianza y mantiene a los clientes satisfechos.<\/p>\r\n                                        <h4>Beneficios clave:<\/h4>\r\n                                        <ul>\r\n                                                                        <li>\r\n                                <span class=\"fa-li\"><i class=\"fas fa-check-circle\"><\/i><\/span>\r\n                                Seguimiento de entregas en tiempo real                            <\/li>\r\n                                                                                                <li>\r\n                                <span class=\"fa-li\"><i class=\"fas fa-check-circle\"><\/i><\/span>\r\n                                Mejorar la comunicaci\u00f3n con el cliente                            <\/li>\r\n                                                                                                <li>\r\n                                <span class=\"fa-li\"><i class=\"fas fa-check-circle\"><\/i><\/span>\r\n                                Proporcionar un servicio confiable y fiable                            <\/li>\r\n                                                            <\/ul>\r\n                                        <a href=\"#formmodal\" class=\"btn btn-green btn-inline\">\r\n                    Contacte a nuestro equipo                <\/a>\r\n                    <\/div>  \r\n                    <div class=\"image\">\r\n                <img decoding=\"async\" src=\"https:\/\/www.quartix.com\/content\/uploads\/2024\/05\/ES-driving-style.png\" alt=\"ES driving style\">\r\n            <\/div>\r\n            <\/div>\r\n<\/section>\n\n<section  class=\"qtx-pagebuilder-section qtx-pagebuilder-section-reviews\">\r\n<div class=\"reviews\">\r\n            <h2>Rese\u00f1as reales <span class=\"green bold\">de clientes reales<\/span><\/h2>\r\n                <div class=\"images\">\r\n                                <img decoding=\"async\" src=\"https:\/\/www.quartix.com\/content\/uploads\/2024\/05\/Image-15.png\" alt=\"\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/www.quartix.com\/content\/uploads\/2024\/05\/Image-17.png\" alt=\"\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/www.quartix.com\/content\/uploads\/2024\/05\/Image-16.png\" alt=\"\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/www.quartix.com\/content\/uploads\/2024\/05\/Image-12.png\" alt=\"\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/www.quartix.com\/content\/uploads\/2024\/05\/Image-11.png\" alt=\"\">\r\n                                    <img decoding=\"async\" src=\"https:\/\/www.quartix.com\/content\/uploads\/2024\/05\/Image-18.png\" alt=\"\">\r\n                        <\/div>\r\n    \r\n    <div class=\"widthwrapper\">\r\n        <div class=\"slider\">\r\n                        <div class=\"review\">\r\n                                    <h3>Siempre se proporciona un excelente servicio<\/h3>\r\n                                                    <p>He utilizado los servicios de Quartix durante a\u00f1os. Siempre se proporciona un excelente servicio, excelente gerente de cuenta y equipo de servicio al cliente. Los ingenieros son excelentes y siempre llegan a tiempo, excelente comunicaci\u00f3n durante todo el proceso. Buenas funciones de informes, nunca hay problemas. Gracias por su servicio continuo, Quartix.<\/p>\r\n                                                    <p class=\"author\">Ms Joanne Lindsay<\/p>\r\n                            <\/div>\r\n                        <div class=\"review\">\r\n                                    <h3>Buen servicio de Quartix<\/h3>\r\n                                                    <p>Quartix tiene una forma de trabajar simple y proactiva. Solicit\u00e9 que suministraran algunos art\u00edculos (con costo), me enviaron un presupuesto y enviaron los art\u00edculos el mismo d\u00eda, con un tiempo de entrega muy corto. Todos con los que he tratado parecen querer ayudar.<\/p>\r\n                                                    <p class=\"author\">Darren<\/p>\r\n                            <\/div>\r\n                        <div class=\"review\">\r\n                                    <h3>He estado con Quartix durante unos a\u00f1os\u2026<\/h3>\r\n                                                    <p>He estado con Quartix durante unos a\u00f1os y he disfrutado de su servicio, tanto el servicio al cliente como el t\u00e9cnico han sido encantadores de tratar. Tuve un problema reciente que se resolvi\u00f3 en mi beneficio tambi\u00e9n, as\u00ed que m\u00e1s que feliz. Gracias Quartix.<\/p>\r\n                                                    <p class=\"author\">Nick Fletcher<\/p>\r\n                            <\/div>\r\n                        <div class=\"review\">\r\n                                    <h3>Hemos utilizado Quartix durante m\u00e1s de 10 a\u00f1os. Servicio de 5 estrellas.<\/h3>\r\n                                                    <p>Hemos utilizado Quartix durante m\u00e1s de 10 a\u00f1os, el servicio al cliente es excepcional. Nunca hemos tenido problemas con los rastreadores, los pocos casos a lo largo de los a\u00f1os han sido resueltos r\u00e1pidamente por un ingeniero que acude al lugar.<\/p>\r\n                                                    <p class=\"author\">J C services &#038; Son Ltd<\/p>\r\n                            <\/div>\r\n                    <\/div>  \r\n    <\/div>\r\n            <a href=\"#formmodal\"\r\n        class=\"btn btn-green btn-inline\"\r\n        >\r\n            Empiece hoy mismo        <\/a>\r\n    <\/div>\r\n<\/section>\r\n\r\n<script nonce=\"\" nonce=\"\">\r\n    jQuery(function($) {\r\n        $( document ).ready(function(){\r\n            $('.qtx-pagebuilder-section-reviews .slider').slick({\r\n                arrows: false,\r\n                dots: true,\r\n                slidesToShow: 3,\r\n                slidesToScroll: 1,\r\n                responsive: [\r\n                    {\r\n                    breakpoint: 1024,\r\n                    settings: {\r\n                        slidesToShow: 2,\r\n                        }\r\n                    },\r\n                    {\r\n                    breakpoint: 768,\r\n                    settings: {\r\n                        slidesToShow: 1,\r\n                        } \r\n                    },\r\n                ]\r\n            });\r\n        });\r\n    });\r\n\r\n<\/script>\n\n<section  class=\"qtx-pagebuilder-section qtx-pagebuilder-section-cta-v2 \">\r\n    <div class=\"widthwrapper\">\r\n<div class=\"content\">\r\n    <h2>Quartix es una plataforma r\u00e1pida y f\u00e1cil de usar para empresas con flotas de coches, furgonetas, camiones y camiones grandes.<\/h2>    <p>Siga los veh\u00edculos en tiempo real, supervise a los conductores y planifique rutas f\u00e1cilmente. Ahorre tiempo y aumente la productividad mientras ahorra dinero con resultados probados. \u00a1Comience hoy mismo!<\/p>        <a href=\"#formmodal\" \r\n       class=\"btn btn-green\" \r\n       >\r\n        Empezar    <\/a>\r\n    <\/div>\r\n        <div class=\"image\">\r\n            <img decoding=\"async\" src=\"https:\/\/www.quartix.com\/content\/uploads\/2024\/05\/ES-tablet-with-users.png\" alt=\"ES tablet with users\">\r\n        <\/div>\r\n    <\/div>\r\n<\/section>\n\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<section  class=\"qtx-pagebuilder-section qtx-pagebuilder-section-sticky-tiles stickytilesid372221987\">\r\n    <div class=\"widthwrapper\">\r\n        <div class=\"content contentid372221987\">\r\n            <h2>Un sistema de seguimiento de veh\u00edculos para empresas de servicios y transporte de todos los tama\u00f1os<\/h2>\r\n            <p>M\u00e1s de 30.000 empresas utilizan Quartix para un seguimiento sencillo de veh\u00edculos. Mejore sus operaciones y ahorre tiempo. Rastree sus veh\u00edculos en vivo, observe el comportamiento de los conductores y mantenga su negocio funcionando sin problemas.<\/p>\r\n        <\/div>\r\n        <div class=\"tiles tileid372221987\">\r\n                    <div class=\"tile tile1\">\r\n                <img decoding=\"async\" src=\"https:\/\/www.quartix.com\/content\/uploads\/2024\/05\/ES-dashboards-with-driving-style-on-mob.png\" alt=\"\" \/>\r\n                <h3 class=\"line1\">Para la industria de servicios<\/h3>\r\n                <h3 class=\"line2\">Aumentar la productividad:<\/h3>\r\n                <ul>\r\n                                            <li><span class=\"fa-li\"><i class=\"fas fa-check-circle\"><\/i><\/span>Programar de manera m\u00e1s eficiente<\/li>\r\n                                            <li><span class=\"fa-li\"><i class=\"fas fa-check-circle\"><\/i><\/span>Asignar mejor los recursos<\/li>\r\n                                            <li><span class=\"fa-li\"><i class=\"fas fa-check-circle\"><\/i><\/span>Reducir los costes de combustible<\/li>\r\n                                    <\/ul>\r\n            <\/div>\r\n                        <div class=\"tile tile2\">\r\n                <img decoding=\"async\" src=\"https:\/\/www.quartix.com\/content\/uploads\/2024\/05\/ES-live-tracking-screen.png\" alt=\"ES live tracking screen\" \/>\r\n                <h3 class=\"line1\">Para la industria del transporte<\/h3>\r\n                <h3 class=\"line2\">Mejore la eficiencia y el rendimiento:<\/h3>\r\n                <ul>\r\n                                            <li><span class=\"fa-li\"><i class=\"fas fa-check-circle\"><\/i><\/span>Aproveche al m\u00e1ximo sus veh\u00edculos<\/li>\r\n                                            <li><span class=\"fa-li\"><i class=\"fas fa-check-circle\"><\/i><\/span>Planificar mejor las rutas<\/li>\r\n                                            <li><span class=\"fa-li\"><i class=\"fas fa-check-circle\"><\/i><\/span>Aumentar la satisfacci\u00f3n del cliente<\/li>\r\n                                    <\/ul>\r\n            <\/div>\r\n                    <\/div>\r\n    <\/div>\r\n<\/section>\r\n\r\n","protected":false},"excerpt":{"rendered":"<p>Descubra c\u00f3mo nuestro sistema de gesti\u00f3n de flotas transforma los negocios<\/p>\n","protected":false},"featured_media":0,"template":"templates\/landing-pagebuilder-v2.php","landing-page-category":[],"topic":[],"qtx_campaign":[],"class_list":["post-103725","landing_page","type-landing_page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Seguimiento de Veh\u00edculos Galardonado - Quartix - ES<\/title>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vehicle Tracking 2024 V2\" \/>\n<meta property=\"og:description\" content=\"Descubra c\u00f3mo nuestro sistema de gesti\u00f3n de flotas transforma los negocios\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.quartix.com\/es-es\/in\/seguimiento-de-vehiculos-2024-v2\/\" \/>\n<meta property=\"og:site_name\" content=\"Quartix\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Quartix-USA-374426386097401\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-07T17:39:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@QuartixUSA\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutes\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Seguimiento de Veh\u00edculos Galardonado - Quartix - ES","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"es_ES","og_type":"article","og_title":"Vehicle Tracking 2024 V2","og_description":"Descubra c\u00f3mo nuestro sistema de gesti\u00f3n de flotas transforma los negocios","og_url":"https:\/\/www.quartix.com\/es-es\/in\/seguimiento-de-vehiculos-2024-v2\/","og_site_name":"Quartix","article_publisher":"https:\/\/www.facebook.com\/Quartix-USA-374426386097401\/","article_modified_time":"2024-06-07T17:39:44+00:00","twitter_card":"summary_large_image","twitter_site":"@QuartixUSA","twitter_misc":{"Est. reading time":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.quartix.com\/es-es\/in\/seguimiento-de-vehiculos-2024-v2\/","url":"https:\/\/www.quartix.com\/es-es\/in\/seguimiento-de-vehiculos-2024-v2\/","name":"Seguimiento de Veh\u00edculos Galardonado - Quartix","isPartOf":{"@id":"https:\/\/www.quartix.com\/es-es\/#website"},"datePublished":"2024-05-30T18:37:56+00:00","dateModified":"2024-06-07T17:39:44+00:00","breadcrumb":{"@id":"https:\/\/www.quartix.com\/es-es\/in\/seguimiento-de-vehiculos-2024-v2\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.quartix.com\/es-es\/in\/seguimiento-de-vehiculos-2024-v2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.quartix.com\/es-es\/in\/seguimiento-de-vehiculos-2024-v2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.quartix.com\/es-es\/quartix-localizacion-de-vehiculos-en-tiempo-real\/"},{"@type":"ListItem","position":2,"name":"Vehicle Tracking 2024 V2"}]},{"@type":"WebSite","@id":"https:\/\/www.quartix.com\/es-es\/#website","url":"https:\/\/www.quartix.com\/es-es\/","name":"Quartix","description":"Real-time vehicle tracking","publisher":{"@id":"https:\/\/www.quartix.com\/es-es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.quartix.com\/es-es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/www.quartix.com\/es-es\/#organization","name":"Quartix","url":"https:\/\/www.quartix.com\/es-es\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/www.quartix.com\/es-es\/#\/schema\/logo\/image\/","url":"https:\/\/www.quartix.com\/content\/uploads\/2019\/02\/quartix-logo-eur.svg","contentUrl":"https:\/\/www.quartix.com\/content\/uploads\/2019\/02\/quartix-logo-eur.svg","width":1,"height":1,"caption":"Quartix"},"image":{"@id":"https:\/\/www.quartix.com\/es-es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Quartix-USA-374426386097401\/","https:\/\/x.com\/QuartixUSA","https:\/\/www.linkedin.com\/company\/5346733\/","https:\/\/www.youtube.com\/channel\/UCzS-_GMfHF4kWiCheyIRrAQ"]}]}},"_links":{"self":[{"href":"https:\/\/www.quartix.com\/es-es\/wp-json\/wp\/v2\/landing_page\/103725","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.quartix.com\/es-es\/wp-json\/wp\/v2\/landing_page"}],"about":[{"href":"https:\/\/www.quartix.com\/es-es\/wp-json\/wp\/v2\/types\/landing_page"}],"wp:attachment":[{"href":"https:\/\/www.quartix.com\/es-es\/wp-json\/wp\/v2\/media?parent=103725"}],"wp:term":[{"taxonomy":"landing-page-category","embeddable":true,"href":"https:\/\/www.quartix.com\/es-es\/wp-json\/wp\/v2\/landing-page-category?post=103725"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/www.quartix.com\/es-es\/wp-json\/wp\/v2\/topic?post=103725"},{"taxonomy":"qtx_campaign","embeddable":true,"href":"https:\/\/www.quartix.com\/es-es\/wp-json\/wp\/v2\/qtx_campaign?post=103725"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}